{"id":199591,"date":"2023-12-14T17:23:47","date_gmt":"2023-12-14T16:23:47","guid":{"rendered":"https:\/\/aeeolica.org\/?p=199591"},"modified":"2023-12-14T17:24:11","modified_gmt":"2023-12-14T16:24:11","slug":"fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol","status":"publish","type":"post","link":"https:\/\/aeeolica.org\/en\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\/","title":{"rendered":"Fundeen desarrollar\u00e1 en los pr\u00f3ximos dos a\u00f1os m\u00e1s de 8 proyectos e\u00f3licos en el territorio espa\u00f1ol"},"content":{"rendered":"\n<p>Fundeen la plataforma l\u00edder de coinversi\u00f3n en proyectos de energ\u00eda renovable, cuenta con&nbsp;141 proyectos de participaci\u00f3n local a ser financiados hasta 2026, con un total de 514,5 millones de euros de financiaci\u00f3n objetivo, donde se desarrollar\u00e1n <strong>8 proyectos e\u00f3licos <\/strong>en Catalu\u00f1aque suman una potencia total de 390,3 MW, evitando m\u00e1s de 25.9615 toneladas de CO2. Estos proyectos se encuentran abiertos a reservas en la plataforma, donde las distintas localidades c\u00f3mo Ivorra, Estar\u00e0s, Calongue de Segarra, entre otros. Tendr\u00e1n la prioridad de invertir en estos proyectos. El resto se compone de&nbsp;32 proyectos de inversi\u00f3n global, con una financiaci\u00f3n objetivo de 43 millones de euros.<\/p>\n\n\n\n<p>No obstante, la plataforma prev\u00e9 ofertar 207 millones de euros de financiaci\u00f3n de plantas energ\u00e9ticas en 2024, y una cartera estimada hasta 2026 que asciende a&nbsp;173 proyectos que suman hasta 557,5 millones de euros de financiaci\u00f3n objetivo.<\/p>\n\n\n\n<p>Adem\u00e1s, est\u00e1 finalizando el a\u00f1o con m\u00e1s de 15,000 inversores en su plataforma, un testimonio del respaldo que demuestra el inter\u00e9s y conciencia sobre la importancia de las inversiones en energ\u00edas renovables. En un momento en que la transici\u00f3n hacia fuentes de energ\u00eda m\u00e1s sostenibles es crucial.<\/p>\n\n\n\n<p>M\u00e1s informaci\u00f3n: https:\/\/www.fundeen.com\/invertir-energias-renovables<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/aeeolica.org\/wp-content\/uploads\/2023\/12\/Fundeen-Founders-\u2014-Nacho-y-Adrian-by-Nixae\u00ae-41-1024x683.jpg\" alt=\"\" class=\"wp-image-199589\" srcset=\"https:\/\/aeeolica.org\/wp-content\/uploads\/2023\/12\/Fundeen-Founders-\u2014-Nacho-y-Adrian-by-Nixae\u00ae-41-1024x683.jpg 1024w, https:\/\/aeeolica.org\/wp-content\/uploads\/2023\/12\/Fundeen-Founders-\u2014-Nacho-y-Adrian-by-Nixae\u00ae-41-300x200.jpg 300w, https:\/\/aeeolica.org\/wp-content\/uploads\/2023\/12\/Fundeen-Founders-\u2014-Nacho-y-Adrian-by-Nixae\u00ae-41-scaled-600x400.jpg 600w, https:\/\/aeeolica.org\/wp-content\/uploads\/2023\/12\/Fundeen-Founders-\u2014-Nacho-y-Adrian-by-Nixae\u00ae-41-768x512.jpg 768w, https:\/\/aeeolica.org\/wp-content\/uploads\/2023\/12\/Fundeen-Founders-\u2014-Nacho-y-Adrian-by-Nixae\u00ae-41-1536x1025.jpg 1536w, https:\/\/aeeolica.org\/wp-content\/uploads\/2023\/12\/Fundeen-Founders-\u2014-Nacho-y-Adrian-by-Nixae\u00ae-41-2048x1366.jpg 2048w, https:\/\/aeeolica.org\/wp-content\/uploads\/2023\/12\/Fundeen-Founders-\u2014-Nacho-y-Adrian-by-Nixae\u00ae-41-1080x720.jpg 1080w, https:\/\/aeeolica.org\/wp-content\/uploads\/2023\/12\/Fundeen-Founders-\u2014-Nacho-y-Adrian-by-Nixae\u00ae-41-1280x854.jpg 1280w, https:\/\/aeeolica.org\/wp-content\/uploads\/2023\/12\/Fundeen-Founders-\u2014-Nacho-y-Adrian-by-Nixae\u00ae-41-980x654.jpg 980w, https:\/\/aeeolica.org\/wp-content\/uploads\/2023\/12\/Fundeen-Founders-\u2014-Nacho-y-Adrian-by-Nixae\u00ae-41-480x320.jpg 480w, https:\/\/aeeolica.org\/wp-content\/uploads\/2023\/12\/Fundeen-Founders-\u2014-Nacho-y-Adrian-by-Nixae\u00ae-41-1320x880.jpg 1320w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Los fundadores de Fundeen: Nacho Bautista y Adri\u00e1n Bautista (de izquierda a derecha)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fundeen la plataforma l\u00edder de coinversi\u00f3n en proyectos de energ\u00eda renovable, cuenta con&nbsp;141 proyectos de participaci\u00f3n local a ser financiados hasta 2026, con un total de 514,5 millones de euros [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":199587,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[480],"tags":[],"class_list":["post-199591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsletter-diciembre-2023"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fundeen desarrollar\u00e1 en los pr\u00f3ximos dos a\u00f1os m\u00e1s de 8 proyectos e\u00f3licos en el territorio espa\u00f1ol - Asociaci\u00f3n Empresarial E\u00f3lica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aeeolica.org\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fundeen desarrollar\u00e1 en los pr\u00f3ximos dos a\u00f1os m\u00e1s de 8 proyectos e\u00f3licos en el territorio espa\u00f1ol - Asociaci\u00f3n Empresarial E\u00f3lica\" \/>\n<meta property=\"og:description\" content=\"Fundeen la plataforma l\u00edder de coinversi\u00f3n en proyectos de energ\u00eda renovable, cuenta con&nbsp;141 proyectos de participaci\u00f3n local a ser financiados hasta 2026, con un total de 514,5 millones de euros [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aeeolica.org\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\/\" \/>\n<meta property=\"og:site_name\" content=\"Asociaci\u00f3n Empresarial E\u00f3lica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/aeeolica\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-14T16:23:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-14T16:24:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aeeolica.org\/wp-content\/uploads\/2023\/12\/EOLICASjpg-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1686\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Morante D\u00edaz, Mar\u00eda del Mar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@aeeolica\" \/>\n<meta name=\"twitter:site\" content=\"@aeeolica\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Morante D\u00edaz, Mar\u00eda del Mar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aeeolica.org\\\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aeeolica.org\\\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\\\/\"},\"author\":{\"name\":\"Morante D\u00edaz, Mar\u00eda del Mar\",\"@id\":\"https:\\\/\\\/aeeolica.org\\\/#\\\/schema\\\/person\\\/064b26f21f7ed52e0b3854e6b52f9772\"},\"headline\":\"Fundeen desarrollar\u00e1 en los pr\u00f3ximos dos a\u00f1os m\u00e1s de 8 proyectos e\u00f3licos en el territorio espa\u00f1ol\",\"datePublished\":\"2023-12-14T16:23:47+00:00\",\"dateModified\":\"2023-12-14T16:24:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aeeolica.org\\\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\\\/\"},\"wordCount\":247,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\\\/\\\/aeeolica.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/aeeolica.org\\\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aeeolica.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/EOLICASjpg-scaled.jpg\",\"articleSection\":[\"Newsletter Diciembre 2023\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/aeeolica.org\\\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aeeolica.org\\\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\\\/\",\"url\":\"https:\\\/\\\/aeeolica.org\\\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\\\/\",\"name\":\"Fundeen desarrollar\u00e1 en los pr\u00f3ximos dos a\u00f1os m\u00e1s de 8 proyectos e\u00f3licos en el territorio espa\u00f1ol - Asociaci\u00f3n Empresarial E\u00f3lica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aeeolica.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aeeolica.org\\\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aeeolica.org\\\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aeeolica.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/EOLICASjpg-scaled.jpg\",\"datePublished\":\"2023-12-14T16:23:47+00:00\",\"dateModified\":\"2023-12-14T16:24:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aeeolica.org\\\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aeeolica.org\\\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aeeolica.org\\\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aeeolica.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/EOLICASjpg-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/aeeolica.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/EOLICASjpg-scaled.jpg\",\"width\":2560,\"height\":1686},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aeeolica.org\\\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/aeeolica.org\\\/en\\\/inicio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fundeen desarrollar\u00e1 en los pr\u00f3ximos dos a\u00f1os m\u00e1s de 8 proyectos e\u00f3licos en el territorio espa\u00f1ol\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aeeolica.org\\\/#website\",\"url\":\"https:\\\/\\\/aeeolica.org\\\/\",\"name\":\"Asociaci\u00f3n Empresarial E\u00f3lica\",\"description\":\"AEE Asociaci\u00f3n Empresarial E\u00f3lica\",\"publisher\":{\"@id\":\"https:\\\/\\\/aeeolica.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aeeolica.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aeeolica.org\\\/#organization\",\"name\":\"Asociaci\u00f3n Empresarial E\u00f3lica\",\"url\":\"https:\\\/\\\/aeeolica.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aeeolica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aeeolica.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logo-aee.png\",\"contentUrl\":\"https:\\\/\\\/aeeolica.org\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/logo-aee.png\",\"width\":180,\"height\":78,\"caption\":\"Asociaci\u00f3n Empresarial E\u00f3lica\"},\"image\":{\"@id\":\"https:\\\/\\\/aeeolica.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/aeeolica\",\"https:\\\/\\\/x.com\\\/aeeolica\",\"https:\\\/\\\/www.instagram.com\\\/aeeolica\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/aee-asociaci\u00f3n-empresarial-e\u00f3lica-6830946b\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/AEEolica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aeeolica.org\\\/#\\\/schema\\\/person\\\/064b26f21f7ed52e0b3854e6b52f9772\",\"name\":\"Morante D\u00edaz, Mar\u00eda del Mar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8bfd23e1c4bf5aa0b9314f1c5c9d644e62672831e6a512513954c3f15dffdd5a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8bfd23e1c4bf5aa0b9314f1c5c9d644e62672831e6a512513954c3f15dffdd5a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8bfd23e1c4bf5aa0b9314f1c5c9d644e62672831e6a512513954c3f15dffdd5a?s=96&d=mm&r=g\",\"caption\":\"Morante D\u00edaz, Mar\u00eda del Mar\"},\"url\":\"https:\\\/\\\/aeeolica.org\\\/en\\\/author\\\/mar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fundeen desarrollar\u00e1 en los pr\u00f3ximos dos a\u00f1os m\u00e1s de 8 proyectos e\u00f3licos en el territorio espa\u00f1ol - Asociaci\u00f3n Empresarial E\u00f3lica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aeeolica.org\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\/","og_locale":"en_US","og_type":"article","og_title":"Fundeen desarrollar\u00e1 en los pr\u00f3ximos dos a\u00f1os m\u00e1s de 8 proyectos e\u00f3licos en el territorio espa\u00f1ol - Asociaci\u00f3n Empresarial E\u00f3lica","og_description":"Fundeen la plataforma l\u00edder de coinversi\u00f3n en proyectos de energ\u00eda renovable, cuenta con&nbsp;141 proyectos de participaci\u00f3n local a ser financiados hasta 2026, con un total de 514,5 millones de euros [&hellip;]","og_url":"https:\/\/aeeolica.org\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\/","og_site_name":"Asociaci\u00f3n Empresarial E\u00f3lica","article_publisher":"https:\/\/www.facebook.com\/aeeolica","article_published_time":"2023-12-14T16:23:47+00:00","article_modified_time":"2023-12-14T16:24:11+00:00","og_image":[{"width":2560,"height":1686,"url":"https:\/\/aeeolica.org\/wp-content\/uploads\/2023\/12\/EOLICASjpg-scaled.jpg","type":"image\/jpeg"}],"author":"Morante D\u00edaz, Mar\u00eda del Mar","twitter_card":"summary_large_image","twitter_creator":"@aeeolica","twitter_site":"@aeeolica","twitter_misc":{"Written by":"Morante D\u00edaz, Mar\u00eda del Mar","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aeeolica.org\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\/#article","isPartOf":{"@id":"https:\/\/aeeolica.org\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\/"},"author":{"name":"Morante D\u00edaz, Mar\u00eda del Mar","@id":"https:\/\/aeeolica.org\/#\/schema\/person\/064b26f21f7ed52e0b3854e6b52f9772"},"headline":"Fundeen desarrollar\u00e1 en los pr\u00f3ximos dos a\u00f1os m\u00e1s de 8 proyectos e\u00f3licos en el territorio espa\u00f1ol","datePublished":"2023-12-14T16:23:47+00:00","dateModified":"2023-12-14T16:24:11+00:00","mainEntityOfPage":{"@id":"https:\/\/aeeolica.org\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\/"},"wordCount":247,"commentCount":2,"publisher":{"@id":"https:\/\/aeeolica.org\/#organization"},"image":{"@id":"https:\/\/aeeolica.org\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\/#primaryimage"},"thumbnailUrl":"https:\/\/aeeolica.org\/wp-content\/uploads\/2023\/12\/EOLICASjpg-scaled.jpg","articleSection":["Newsletter Diciembre 2023"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/aeeolica.org\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/aeeolica.org\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\/","url":"https:\/\/aeeolica.org\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\/","name":"Fundeen desarrollar\u00e1 en los pr\u00f3ximos dos a\u00f1os m\u00e1s de 8 proyectos e\u00f3licos en el territorio espa\u00f1ol - Asociaci\u00f3n Empresarial E\u00f3lica","isPartOf":{"@id":"https:\/\/aeeolica.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aeeolica.org\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\/#primaryimage"},"image":{"@id":"https:\/\/aeeolica.org\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\/#primaryimage"},"thumbnailUrl":"https:\/\/aeeolica.org\/wp-content\/uploads\/2023\/12\/EOLICASjpg-scaled.jpg","datePublished":"2023-12-14T16:23:47+00:00","dateModified":"2023-12-14T16:24:11+00:00","breadcrumb":{"@id":"https:\/\/aeeolica.org\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aeeolica.org\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aeeolica.org\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\/#primaryimage","url":"https:\/\/aeeolica.org\/wp-content\/uploads\/2023\/12\/EOLICASjpg-scaled.jpg","contentUrl":"https:\/\/aeeolica.org\/wp-content\/uploads\/2023\/12\/EOLICASjpg-scaled.jpg","width":2560,"height":1686},{"@type":"BreadcrumbList","@id":"https:\/\/aeeolica.org\/fundeen-desarrollara-en-los-proximos-dos-anos-mas-de-8-proyectos-eolicos-en-el-territorio-espanol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/aeeolica.org\/en\/inicio\/"},{"@type":"ListItem","position":2,"name":"Fundeen desarrollar\u00e1 en los pr\u00f3ximos dos a\u00f1os m\u00e1s de 8 proyectos e\u00f3licos en el territorio espa\u00f1ol"}]},{"@type":"WebSite","@id":"https:\/\/aeeolica.org\/#website","url":"https:\/\/aeeolica.org\/","name":"Asociaci\u00f3n Empresarial E\u00f3lica","description":"AEE Asociaci\u00f3n Empresarial E\u00f3lica","publisher":{"@id":"https:\/\/aeeolica.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aeeolica.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/aeeolica.org\/#organization","name":"Asociaci\u00f3n Empresarial E\u00f3lica","url":"https:\/\/aeeolica.org\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aeeolica.org\/#\/schema\/logo\/image\/","url":"https:\/\/aeeolica.org\/wp-content\/uploads\/2021\/08\/logo-aee.png","contentUrl":"https:\/\/aeeolica.org\/wp-content\/uploads\/2021\/08\/logo-aee.png","width":180,"height":78,"caption":"Asociaci\u00f3n Empresarial E\u00f3lica"},"image":{"@id":"https:\/\/aeeolica.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/aeeolica","https:\/\/x.com\/aeeolica","https:\/\/www.instagram.com\/aeeolica\/","https:\/\/www.linkedin.com\/in\/aee-asociaci\u00f3n-empresarial-e\u00f3lica-6830946b\/","https:\/\/www.youtube.com\/user\/AEEolica"]},{"@type":"Person","@id":"https:\/\/aeeolica.org\/#\/schema\/person\/064b26f21f7ed52e0b3854e6b52f9772","name":"Morante D\u00edaz, Mar\u00eda del Mar","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8bfd23e1c4bf5aa0b9314f1c5c9d644e62672831e6a512513954c3f15dffdd5a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8bfd23e1c4bf5aa0b9314f1c5c9d644e62672831e6a512513954c3f15dffdd5a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8bfd23e1c4bf5aa0b9314f1c5c9d644e62672831e6a512513954c3f15dffdd5a?s=96&d=mm&r=g","caption":"Morante D\u00edaz, Mar\u00eda del Mar"},"url":"https:\/\/aeeolica.org\/en\/author\/mar\/"}]}},"_links":{"self":[{"href":"https:\/\/aeeolica.org\/en\/wp-json\/wp\/v2\/posts\/199591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aeeolica.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aeeolica.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aeeolica.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aeeolica.org\/en\/wp-json\/wp\/v2\/comments?post=199591"}],"version-history":[{"count":0,"href":"https:\/\/aeeolica.org\/en\/wp-json\/wp\/v2\/posts\/199591\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aeeolica.org\/en\/wp-json\/wp\/v2\/media\/199587"}],"wp:attachment":[{"href":"https:\/\/aeeolica.org\/en\/wp-json\/wp\/v2\/media?parent=199591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aeeolica.org\/en\/wp-json\/wp\/v2\/categories?post=199591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aeeolica.org\/en\/wp-json\/wp\/v2\/tags?post=199591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}